{"id":22122,"date":"2024-03-04T14:52:51","date_gmt":"2024-03-04T14:52:51","guid":{"rendered":"https:\/\/voetballegends.nl\/wordpress\/?post_type=cpt_portfolio&#038;p=22122"},"modified":"2024-03-04T14:52:52","modified_gmt":"2024-03-04T14:52:52","slug":"ajax-sjaak-swart","status":"publish","type":"cpt_portfolio","link":"https:\/\/voetballegends.nl\/wordpress\/portfolio\/ajax-sjaak-swart\/","title":{"rendered":"Ajax Sjaak Swart"},"content":{"rendered":"<p>Fabrikant Monty Factories Leiderdorp <\/p><p>jaar 1963<\/p><p>serie Voetballers\/elftallen (met rode achterkant)<\/p><p>formaat 5,5 x 8,5 cm<\/p>","protected":false},"excerpt":{"rendered":"<p>Fabrikant Monty Factories Leiderdorp jaar 1963 serie Voetballers\/elftallen (met rode achterkant) formaat 5,5 x 8,5 cm<\/p>\n","protected":false},"author":2,"featured_media":22124,"comment_status":"closed","ping_status":"closed","template":"","cpt_portfolio_group":[180,207],"class_list":["post-22122","cpt_portfolio","type-cpt_portfolio","status-publish","has-post-thumbnail","hentry","cpt_portfolio_group-monty","cpt_portfolio_group-voetballers-elftallen-kaarten-spirograaf"],"_links":{"self":[{"href":"https:\/\/voetballegends.nl\/wordpress\/wp-json\/wp\/v2\/cpt_portfolio\/22122","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/voetballegends.nl\/wordpress\/wp-json\/wp\/v2\/cpt_portfolio"}],"about":[{"href":"https:\/\/voetballegends.nl\/wordpress\/wp-json\/wp\/v2\/types\/cpt_portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/voetballegends.nl\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/voetballegends.nl\/wordpress\/wp-json\/wp\/v2\/comments?post=22122"}],"version-history":[{"count":1,"href":"https:\/\/voetballegends.nl\/wordpress\/wp-json\/wp\/v2\/cpt_portfolio\/22122\/revisions"}],"predecessor-version":[{"id":22125,"href":"https:\/\/voetballegends.nl\/wordpress\/wp-json\/wp\/v2\/cpt_portfolio\/22122\/revisions\/22125"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/voetballegends.nl\/wordpress\/wp-json\/wp\/v2\/media\/22124"}],"wp:attachment":[{"href":"https:\/\/voetballegends.nl\/wordpress\/wp-json\/wp\/v2\/media?parent=22122"}],"wp:term":[{"taxonomy":"cpt_portfolio_group","embeddable":true,"href":"https:\/\/voetballegends.nl\/wordpress\/wp-json\/wp\/v2\/cpt_portfolio_group?post=22122"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}