{"id":7671,"date":"2023-12-11T14:39:47","date_gmt":"2023-12-11T14:39:47","guid":{"rendered":"https:\/\/voetballegends.nl\/wordpress\/?post_type=cpt_portfolio&#038;p=7671"},"modified":"2023-12-11T14:39:47","modified_gmt":"2023-12-11T14:39:47","slug":"feyenoord-rotterdam-kampioen","status":"publish","type":"cpt_portfolio","link":"https:\/\/voetballegends.nl\/wordpress\/portfolio\/feyenoord-rotterdam-kampioen\/","title":{"rendered":"Feyenoord Rotterdam Kampioen"},"content":{"rendered":"<p>Fabrikant Batco<\/p><p>jaar 1931 &#8211; 1932 <\/p><p>serie 1e klassers <\/p><p>formaat 25 x 16 cm<\/p>","protected":false},"excerpt":{"rendered":"<p>Fabrikant Batco jaar 1931 &#8211; 1932 serie 1e klassers formaat 25 x 16 cm<\/p>\n","protected":false},"author":2,"featured_media":7672,"comment_status":"closed","ping_status":"closed","template":"","cpt_portfolio_group":[93,94],"class_list":["post-7671","cpt_portfolio","type-cpt_portfolio","status-publish","has-post-thumbnail","hentry","cpt_portfolio_group-batco","cpt_portfolio_group-elftallen-1e-klasse"],"_links":{"self":[{"href":"https:\/\/voetballegends.nl\/wordpress\/wp-json\/wp\/v2\/cpt_portfolio\/7671","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/voetballegends.nl\/wordpress\/wp-json\/wp\/v2\/cpt_portfolio"}],"about":[{"href":"https:\/\/voetballegends.nl\/wordpress\/wp-json\/wp\/v2\/types\/cpt_portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/voetballegends.nl\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/voetballegends.nl\/wordpress\/wp-json\/wp\/v2\/comments?post=7671"}],"version-history":[{"count":1,"href":"https:\/\/voetballegends.nl\/wordpress\/wp-json\/wp\/v2\/cpt_portfolio\/7671\/revisions"}],"predecessor-version":[{"id":7673,"href":"https:\/\/voetballegends.nl\/wordpress\/wp-json\/wp\/v2\/cpt_portfolio\/7671\/revisions\/7673"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/voetballegends.nl\/wordpress\/wp-json\/wp\/v2\/media\/7672"}],"wp:attachment":[{"href":"https:\/\/voetballegends.nl\/wordpress\/wp-json\/wp\/v2\/media?parent=7671"}],"wp:term":[{"taxonomy":"cpt_portfolio_group","embeddable":true,"href":"https:\/\/voetballegends.nl\/wordpress\/wp-json\/wp\/v2\/cpt_portfolio_group?post=7671"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}