{"id":210,"count":20,"description":"","link":"https:\/\/voetballegends.nl\/wordpress\/portfolio_group\/monty\/elftallen-diversen\/","name":"Voetbalalbum Eredivisie Elftallen 1956 - 1957","slug":"elftallen-diversen","taxonomy":"cpt_portfolio_group","parent":180,"meta":[],"_links":{"self":[{"href":"https:\/\/voetballegends.nl\/wordpress\/wp-json\/wp\/v2\/cpt_portfolio_group\/210","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/voetballegends.nl\/wordpress\/wp-json\/wp\/v2\/cpt_portfolio_group"}],"about":[{"href":"https:\/\/voetballegends.nl\/wordpress\/wp-json\/wp\/v2\/taxonomies\/cpt_portfolio_group"}],"up":[{"embeddable":true,"href":"https:\/\/voetballegends.nl\/wordpress\/wp-json\/wp\/v2\/cpt_portfolio_group\/180"}],"wp:post_type":[{"href":"https:\/\/voetballegends.nl\/wordpress\/wp-json\/wp\/v2\/cpt_portfolio?cpt_portfolio_group=210"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}