{"id":50807,"date":"2025-05-08T16:24:34","date_gmt":"2025-05-08T14:24:34","guid":{"rendered":"https:\/\/voetballegends.nl\/wordpress\/?p=50807"},"modified":"2025-05-08T16:24:35","modified_gmt":"2025-05-08T14:24:35","slug":"benfica-feyenoord-8-5-1963","status":"publish","type":"post","link":"https:\/\/voetballegends.nl\/wordpress\/benfica-feyenoord-8-5-1963\/","title":{"rendered":"Benfica &#8211; Feyenoord (8-5-1963)"},"content":{"rendered":"<p>Vandaag in 1963 speelde Feyenoord in Lissabon de halve finale van de Europa Cup 1 tegen Benfica (foto Nationaal Archief). Door een 3-1 nederlaag (doelpunt van Feyenoord van Frans Bouwmeester) bereikte Benfica de finale. Vele Feyenoord supporters reisden destijds via de boot naar Lissabon, waardoor deze wedstrijd ook bekend staat als de \u201cgeboorte van het legioen\u201d.<\/p>","protected":false},"excerpt":{"rendered":"<p>Vandaag in 1963 speelde Feyenoord in Lissabon de halve finale van de Europa Cup 1 tegen Benfica (foto Nationaal Archief). Door een 3-1 nederlaag (doelpunt van Feyenoord van Frans Bouwmeester) bereikte Benfica de finale. Vele Feyenoord supporters reisden destijds via de boot naar Lissabon, waardoor&hellip;<\/p>\n","protected":false},"author":3,"featured_media":50808,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[90],"tags":[630,325],"class_list":["post-50807","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vandaag","tag-benfica","tag-feyenoord"],"_links":{"self":[{"href":"https:\/\/voetballegends.nl\/wordpress\/wp-json\/wp\/v2\/posts\/50807","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/voetballegends.nl\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/voetballegends.nl\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/voetballegends.nl\/wordpress\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/voetballegends.nl\/wordpress\/wp-json\/wp\/v2\/comments?post=50807"}],"version-history":[{"count":1,"href":"https:\/\/voetballegends.nl\/wordpress\/wp-json\/wp\/v2\/posts\/50807\/revisions"}],"predecessor-version":[{"id":50809,"href":"https:\/\/voetballegends.nl\/wordpress\/wp-json\/wp\/v2\/posts\/50807\/revisions\/50809"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/voetballegends.nl\/wordpress\/wp-json\/wp\/v2\/media\/50808"}],"wp:attachment":[{"href":"https:\/\/voetballegends.nl\/wordpress\/wp-json\/wp\/v2\/media?parent=50807"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/voetballegends.nl\/wordpress\/wp-json\/wp\/v2\/categories?post=50807"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/voetballegends.nl\/wordpress\/wp-json\/wp\/v2\/tags?post=50807"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}